{"id":70451,"date":"2012-05-01T08:34:25","date_gmt":"2012-05-01T08:34:25","guid":{"rendered":"http:\/\/www.martin-koser.de\/BMID\/2012\/05\/lesenswerte-analyse\/"},"modified":"2012-05-06T00:00:56","modified_gmt":"2012-05-05T22:00:56","slug":"lesenswerte-analyse","status":"publish","type":"post","link":"http:\/\/www.martin-koser.de\/BMID\/2012\/05\/lesenswerte-analyse\/","title":{"rendered":"lesenswerte Analyse"},"content":{"rendered":"<p>&quot;Mit den M&ouml;glichkeiten der Vernetzung im Web erh&ouml;ht sich allerdings die Wahrscheinlichkeit enorm, auf kluge und weise Menschen zu sto&szlig;en, die einen hilfreichen Beitrag zu einem Thema leisten k&ouml;nnen. Es reduziert die M&ouml;glichkeiten der Meinungsdiktatoren in Wirtschaft, Politik und Medien, Wissen zu horten und &uuml;ber monopolisiertes Wissen Macht auszu&uuml;ben. Das Ganze ist unglaublich anstrengend. Wer sich gegen die vielen Stimmen im Netz durchsetzen will, muss sehr gute Argumente haben und ein wahrer &Uuml;berzeugungsk&uuml;nstler sein beim Bohren dicker Bretter, wie es Max Weber formuliert hat. Bedenkentr&auml;ger sind aber unverzichtbar, um Innovationen und neue Ideen durchzusetzen&quot;<\/p>\n<p style='clear:both;'>\n<p style='margin-bottom:5px;'><strong>Embedded Link<\/strong><\/p>\n<div style='height:120px;width:120px;overflow:hidden;float:left;margin-top:0px;padding-top:0px;margin-right:10px;vertical-align:top;text-align:center;clear:both;'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img style='max-width:none;' src='http:\/\/images0-focus-opensocial.googleusercontent.com\/gadgets\/proxy?container=focus&#038;gadget=a&#038;resize_h=100&#038;url=http%3A%2F%2Fwww.netzpiloten.de%2Fwp-content%2Fuploads%2F2012%2F05%2Fwater-drops.jpg' border='0' \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<a href='http:\/\/www.netzpiloten.de\/2012\/05\/01\/liquide-demokratie-statt-mauer-taktik-flussiges-wissen\/'>Liquide Demokratie statt Mauer-Taktik: Fl&uuml;ssiges Wissen | Netzpiloten.de &#8211; das Beste aus Blogs, Videos, Musik und Web 2.0<\/a><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\tLiquide Demokratie ist unglaublich anstrengend \u2013 aber sie lohnt sich, denn im Schwarm gibt es wertvolles Expertenwissen. Wie gro&szlig; der Widerstand gegen diese\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p style='clear:both;'> <strong>Google+:<\/strong> <a href='https:\/\/plus.google.com\/103404136100035905482\/posts\/K1AQyWMjgGK' target='_new'>View post on Google+<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&quot;Mit den M&ouml;glichkeiten der Vernetzung im Web erh&ouml;ht sich allerdings die Wahrscheinlichkeit enorm, auf kluge und weise Menschen zu sto&szlig;en, die einen hilfreichen Beitrag zu einem Thema leisten k&ouml;nnen. Es reduziert die M&ouml;glichkeiten der Meinungsdiktatoren in Wirtschaft, Politik und Medien, Wissen zu horten und &uuml;ber monopolisiertes Wissen Macht auszu&uuml;ben. Das Ganze ist unglaublich anstrengend. Wer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[653],"tags":[],"_links":{"self":[{"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/posts\/70451"}],"collection":[{"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/comments?post=70451"}],"version-history":[{"count":9,"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/posts\/70451\/revisions"}],"predecessor-version":[{"id":70617,"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/posts\/70451\/revisions\/70617"}],"wp:attachment":[{"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/media?parent=70451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/categories?post=70451"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.martin-koser.de\/BMID\/wp-json\/wp\/v2\/tags?post=70451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}